{"id":90908,"date":"2026-05-09T22:18:54","date_gmt":"2026-05-10T05:18:54","guid":{"rendered":"https:\/\/www.cloudbeds.com\/?post_type=customers&#038;p=90908"},"modified":"2026-05-25T10:52:25","modified_gmt":"2026-05-25T17:52:25","slug":"bogentrakt-hostel","status":"publish","type":"customers","link":"https:\/\/www.cloudbeds.com\/fr\/customers\/bogentrakt-hostel\/","title":{"rendered":"Auberge de jeunesse Bogentrakt : transformer la prison la plus dure de Suisse en un lieu de libert\u00e9 accueillant"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez comment l&rsquo;\u00e9quipe \u00e0 l&rsquo;origine de l&rsquo;auberge de jeunesse Bogentrakt, transform\u00e9e en prison, est pass\u00e9e de cinq syst\u00e8mes diff\u00e9rents \u00e0 un syst\u00e8me unique.<\/p>\n","protected":false},"author":118,"featured_media":40163,"comment_status":"closed","ping_status":"closed","template":"","categories":[],"tags":[],"class_list":["post-90908","customers","type-customers","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Auberge de jeunesse Bogentrakt - T\u00e9moignages d\u2019h\u00f4teliers<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez comment Bogentrakt utilise Cloudbeds pour gagner du temps, maximiser ses revenus et former rapidement son personnel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cloudbeds.com\/fr\/customers\/bogentrakt-hostel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auberge de jeunesse Bogentrakt - T\u00e9moignages d\u2019h\u00f4teliers\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez comment Bogentrakt utilise Cloudbeds pour gagner du temps, maximiser ses revenus et former rapidement son personnel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cloudbeds.com\/fr\/wp-json\/wp\/v2\/customers\/90908\" \/>\n<meta property=\"og:site_name\" content=\"Cloudbeds\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Cloudbeds\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-25T17:52:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cloudbeds.com\/wp-content\/uploads\/2024\/01\/Screen-Shot-2024-03-25-at-4.19.59-PM-e1711408950820.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1088\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Cloudbeds\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cloudbeds.com\\\/fr\\\/wp-json\\\/wp\\\/v2\\\/customers\\\/90908\",\"url\":\"https:\\\/\\\/www.cloudbeds.com\\\/fr\\\/wp-json\\\/wp\\\/v2\\\/customers\\\/90908\",\"name\":\"Auberge de jeunesse Bogentrakt - T\u00e9moignages d\u2019h\u00f4teliers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cloudbeds.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cloudbeds.com\\\/fr\\\/wp-json\\\/wp\\\/v2\\\/customers\\\/90908#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cloudbeds.com\\\/fr\\\/wp-json\\\/wp\\\/v2\\\/customers\\\/90908#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cloudbeds.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Screen-Shot-2024-03-25-at-4.19.59-PM-e1711408950820.png\",\"datePublished\":\"2026-05-10T05:18:54+00:00\",\"dateModified\":\"2026-05-25T17:52:25+00:00\",\"description\":\"D\u00e9couvrez comment Bogentrakt utilise Cloudbeds pour gagner du temps, maximiser ses revenus et former rapidement son personnel.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cloudbeds.com\\\/fr\\\/wp-json\\\/wp\\\/v2\\\/customers\\\/90908#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cloudbeds.com\\\/fr\\\/wp-json\\\/wp\\\/v2\\\/customers\\\/90908\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cloudbeds.com\\\/fr\\\/wp-json\\\/wp\\\/v2\\\/customers\\\/90908#primaryimage\",\"url\":\"https:\\\/\\\/www.cloudbeds.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Screen-Shot-2024-03-25-at-4.19.59-PM-e1711408950820.png\",\"contentUrl\":\"https:\\\/\\\/www.cloudbeds.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Screen-Shot-2024-03-25-at-4.19.59-PM-e1711408950820.png\",\"width\":1088,\"height\":625,\"caption\":\"Bogentrakt Hotel exterior\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cloudbeds.com\\\/fr\\\/wp-json\\\/wp\\\/v2\\\/customers\\\/90908#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cloudbeds.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Customers\",\"item\":\"https:\\\/\\\/www.cloudbeds.com\\\/fr\\\/customers\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Auberge de jeunesse Bogentrakt : transformer la prison la plus dure de Suisse en un lieu de libert\u00e9 accueillant\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cloudbeds.com\\\/#website\",\"url\":\"https:\\\/\\\/www.cloudbeds.com\\\/\",\"name\":\"Cloudbeds\",\"description\":\"#1 Hotel Management Software - Cloud-Based, Unified Platform\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cloudbeds.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cloudbeds.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cloudbeds.com\\\/#organization\",\"name\":\"Cloudbeds\",\"alternateName\":\"Cloudbeds Digital Arbitrage\",\"url\":\"https:\\\/\\\/www.cloudbeds.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cloudbeds.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cloudbeds.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-footer.svg\",\"contentUrl\":\"https:\\\/\\\/www.cloudbeds.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo-footer.svg\",\"width\":240,\"height\":35,\"caption\":\"Cloudbeds\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cloudbeds.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Cloudbeds\\\/\",\"https:\\\/\\\/x.com\\\/Cloudbeds\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/cloudbeds\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCyfR7GappZBy-uziWO9WLdQ\"],\"description\":\"Cloudbeds is hospitality\u2019s only intelligent growth engine \u2014 a unified platform trusted by the world\u2019s most ambitious hoteliers across 150 countries. Built to challenge the limits of outdated tech stacks, Cloudbeds connects operations, revenue, distribution, and guest experience in one powerful, intuitive system. The platform is enhanced with Signals, a hospitality AI model giving hoteliers the power to anticipate demand, run smarter operations, and craft more personal, profitable guest journeys at scale. Founded in 2012, Cloudbeds has earned top honors from Hotel Tech Report (Top PMS, Hotel Management System, and Channel Manager, 2021\u20132026), the World Travel Awards (World\u2019s Best Hotel PMS Solutions Provider, 2022), and Deloitte\u2019s Technology Fast 500 (2025).\",\"legalName\":\"Cloudbeds Digital Arbitrage\",\"foundingDate\":\"2012-10-10\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"501\",\"maxValue\":\"1000\"},\"publishingPrinciples\":\"https:\\\/\\\/www.cloudbeds.com\\\/es\\\/centro-recursos\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/www.cloudbeds.com\\\/our-story\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Auberge de jeunesse Bogentrakt - T\u00e9moignages d\u2019h\u00f4teliers","description":"D\u00e9couvrez comment Bogentrakt utilise Cloudbeds pour gagner du temps, maximiser ses revenus et former rapidement son personnel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cloudbeds.com\/fr\/customers\/bogentrakt-hostel\/","og_locale":"fr_FR","og_type":"article","og_title":"Auberge de jeunesse Bogentrakt - T\u00e9moignages d\u2019h\u00f4teliers","og_description":"D\u00e9couvrez comment Bogentrakt utilise Cloudbeds pour gagner du temps, maximiser ses revenus et former rapidement son personnel.","og_url":"https:\/\/www.cloudbeds.com\/fr\/wp-json\/wp\/v2\/customers\/90908","og_site_name":"Cloudbeds","article_publisher":"https:\/\/www.facebook.com\/Cloudbeds\/","article_modified_time":"2026-05-25T17:52:25+00:00","og_image":[{"width":1088,"height":625,"url":"https:\/\/www.cloudbeds.com\/wp-content\/uploads\/2024\/01\/Screen-Shot-2024-03-25-at-4.19.59-PM-e1711408950820.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Cloudbeds","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cloudbeds.com\/fr\/wp-json\/wp\/v2\/customers\/90908","url":"https:\/\/www.cloudbeds.com\/fr\/wp-json\/wp\/v2\/customers\/90908","name":"Auberge de jeunesse Bogentrakt - T\u00e9moignages d\u2019h\u00f4teliers","isPartOf":{"@id":"https:\/\/www.cloudbeds.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cloudbeds.com\/fr\/wp-json\/wp\/v2\/customers\/90908#primaryimage"},"image":{"@id":"https:\/\/www.cloudbeds.com\/fr\/wp-json\/wp\/v2\/customers\/90908#primaryimage"},"thumbnailUrl":"https:\/\/www.cloudbeds.com\/wp-content\/uploads\/2024\/01\/Screen-Shot-2024-03-25-at-4.19.59-PM-e1711408950820.png","datePublished":"2026-05-10T05:18:54+00:00","dateModified":"2026-05-25T17:52:25+00:00","description":"D\u00e9couvrez comment Bogentrakt utilise Cloudbeds pour gagner du temps, maximiser ses revenus et former rapidement son personnel.","breadcrumb":{"@id":"https:\/\/www.cloudbeds.com\/fr\/wp-json\/wp\/v2\/customers\/90908#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cloudbeds.com\/fr\/wp-json\/wp\/v2\/customers\/90908"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cloudbeds.com\/fr\/wp-json\/wp\/v2\/customers\/90908#primaryimage","url":"https:\/\/www.cloudbeds.com\/wp-content\/uploads\/2024\/01\/Screen-Shot-2024-03-25-at-4.19.59-PM-e1711408950820.png","contentUrl":"https:\/\/www.cloudbeds.com\/wp-content\/uploads\/2024\/01\/Screen-Shot-2024-03-25-at-4.19.59-PM-e1711408950820.png","width":1088,"height":625,"caption":"Bogentrakt Hotel exterior"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cloudbeds.com\/fr\/wp-json\/wp\/v2\/customers\/90908#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cloudbeds.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Customers","item":"https:\/\/www.cloudbeds.com\/fr\/customers\/"},{"@type":"ListItem","position":3,"name":"Auberge de jeunesse Bogentrakt : transformer la prison la plus dure de Suisse en un lieu de libert\u00e9 accueillant"}]},{"@type":"WebSite","@id":"https:\/\/www.cloudbeds.com\/#website","url":"https:\/\/www.cloudbeds.com\/","name":"Cloudbeds","description":"#1 Hotel Management Software - Cloud-Based, Unified Platform","publisher":{"@id":"https:\/\/www.cloudbeds.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cloudbeds.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cloudbeds.com\/#organization","name":"Cloudbeds","alternateName":"Cloudbeds Digital Arbitrage","url":"https:\/\/www.cloudbeds.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cloudbeds.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.cloudbeds.com\/wp-content\/uploads\/2025\/08\/logo-footer.svg","contentUrl":"https:\/\/www.cloudbeds.com\/wp-content\/uploads\/2025\/08\/logo-footer.svg","width":240,"height":35,"caption":"Cloudbeds"},"image":{"@id":"https:\/\/www.cloudbeds.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Cloudbeds\/","https:\/\/x.com\/Cloudbeds","https:\/\/www.linkedin.com\/company\/cloudbeds\/","https:\/\/www.youtube.com\/channel\/UCyfR7GappZBy-uziWO9WLdQ"],"description":"Cloudbeds is hospitality\u2019s only intelligent growth engine \u2014 a unified platform trusted by the world\u2019s most ambitious hoteliers across 150 countries. Built to challenge the limits of outdated tech stacks, Cloudbeds connects operations, revenue, distribution, and guest experience in one powerful, intuitive system. The platform is enhanced with Signals, a hospitality AI model giving hoteliers the power to anticipate demand, run smarter operations, and craft more personal, profitable guest journeys at scale. Founded in 2012, Cloudbeds has earned top honors from Hotel Tech Report (Top PMS, Hotel Management System, and Channel Manager, 2021\u20132026), the World Travel Awards (World\u2019s Best Hotel PMS Solutions Provider, 2022), and Deloitte\u2019s Technology Fast 500 (2025).","legalName":"Cloudbeds Digital Arbitrage","foundingDate":"2012-10-10","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"501","maxValue":"1000"},"publishingPrinciples":"https:\/\/www.cloudbeds.com\/es\/centro-recursos\/","ownershipFundingInfo":"https:\/\/www.cloudbeds.com\/our-story\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cloudbeds.com\/fr\/wp-json\/wp\/v2\/customers\/90908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cloudbeds.com\/fr\/wp-json\/wp\/v2\/customers"}],"about":[{"href":"https:\/\/www.cloudbeds.com\/fr\/wp-json\/wp\/v2\/types\/customers"}],"author":[{"embeddable":true,"href":"https:\/\/www.cloudbeds.com\/fr\/wp-json\/wp\/v2\/users\/118"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cloudbeds.com\/fr\/wp-json\/wp\/v2\/comments?post=90908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cloudbeds.com\/fr\/wp-json\/wp\/v2\/media\/40163"}],"wp:attachment":[{"href":"https:\/\/www.cloudbeds.com\/fr\/wp-json\/wp\/v2\/media?parent=90908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cloudbeds.com\/fr\/wp-json\/wp\/v2\/categories?post=90908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cloudbeds.com\/fr\/wp-json\/wp\/v2\/tags?post=90908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}